{"id":80593,"date":"2026-07-09T08:55:16","date_gmt":"2026-07-09T01:55:16","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=gallery&#038;p=80593"},"modified":"2026-07-13T08:56:09","modified_gmt":"2026-07-13T01:56:09","slug":"71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1","status":"publish","type":"gallery","link":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/","title":{"rendered":"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS"},"content":{"rendered":"<div id=\"modal-ready\">\n<div class=\"wp-block-columns is-layout-flex wp-container-4\">\n<div class=\"wp-block-column is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-03-1024x683.jpg\" alt=\"\" class=\"wp-image-80577\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-03-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-03-600x400.jpg 600w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-03-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-03-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-03.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-02-1024x683.jpg\" alt=\"\" class=\"wp-image-80574\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-02-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-02-600x400.jpg 600w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-02-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-02-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-02.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-07-1024x683.jpg\" alt=\"\" class=\"wp-image-80589\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-07-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-07-600x400.jpg 600w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-07-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-07-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-07.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-06-1024x683.jpg\" alt=\"\" class=\"wp-image-80586\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-06-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-06-600x400.jpg 600w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-06-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-06-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-06.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-05-1024x683.jpg\" alt=\"\" class=\"wp-image-80583\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-05-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-05-600x400.jpg 600w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-05-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-05-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-05.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-04-1024x683.jpg\" alt=\"\" class=\"wp-image-80580\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-04-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-04-600x400.jpg 600w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-04-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-04-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-04.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>\n<\/div>\n<\/div>","protected":false},"featured_media":80571,"parent":0,"template":"","gallery-type":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T01:56:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1139\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/\",\"url\":\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/\",\"name\":\"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\"},\"datePublished\":\"2026-07-09T01:55:16+00:00\",\"dateModified\":\"2026-07-13T01:56:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.buu.ac.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activity Pictures\",\"item\":\"https:\/\/www.buu.ac.th\/en\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"contentUrl\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/","og_locale":"en_US","og_type":"article","og_title":"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_url":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2026-07-13T01:56:09+00:00","og_image":[{"width":2048,"height":1139,"url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/07\/SCOPUS-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/","url":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/","name":"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2026-07-09T01:55:16+00:00","dateModified":"2026-07-13T01:56:09+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/gallery\/71-%e0%b8%9b%e0%b8%b5-%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b8%82%e0%b8%b8%e0%b8%a1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"Activity Pictures","item":"https:\/\/www.buu.ac.th\/en\/gallery\/"},{"@type":"ListItem","position":3,"name":"71 \u0e1b\u0e35 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 : \u0e02\u0e38\u0e21\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e41\u0e25\u0e30 \u0e1e\u0e34\u0e18\u0e35\u0e41\u0e16\u0e25\u0e07\u0e02\u0e48\u0e32\u0e27 \u201c\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e39\u0e23\u0e1e\u0e32 Burapha Science Journal\u201d\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e43\u0e19\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 SCOPUS"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/gallery\/80593"}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/gallery"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/gallery"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media\/80571"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=80593"}],"wp:term":[{"taxonomy":"gallery-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/gallery-type?post=80593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}