{"id":36248,"date":"2024-05-02T15:05:34","date_gmt":"2024-05-02T08:05:34","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=36248"},"modified":"2024-05-02T15:05:36","modified_gmt":"2024-05-02T08:05:36","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07"},"content":{"rendered":"<div id=\"modal-ready\">\n<p class=\"wp-block-paragraph\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567<\/strong> <\/p>\n\n\n\n<p class=\"has-vivid-red-color has-text-color wp-block-paragraph\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32.\"><\/object><a id=\"wp-block-file--media-f7a14dec-f96a-4bfd-8fa7-3d75d2415f21\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32.pdf\">\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-f7a14dec-f96a-4bfd-8fa7-3d75d2415f21\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n<\/div>","protected":false},"featured_media":0,"parent":0,"template":"","agency":[136],"news-type":[39],"class_list":["post-36248","new","type-new","status-publish","hentry","agency-136","news-type-39"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:description\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567 \u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T08:05:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\\\/\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\\\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#website\"},\"datePublished\":\"2024-05-02T08:05:34+00:00\",\"dateModified\":\"2024-05-02T08:05:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.buu.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_description":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2567 \u0e16\u0e36\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 26 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567 \u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e41\u0e19\u0e1a\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2024-05-02T08:05:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/","name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2024-05-02T08:05:34+00:00","dateModified":"2024-05-02T08:05:36+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%9a%e0%b8%a3%e0%b8%b4%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b8%98%e0%b8%b8%e0%b8%a3%e0%b8%81%e0%b8%b4%e0%b8%88-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e04\u0e13\u0e30\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49 \u0e08\u0e33\u0e19\u0e27\u0e19 40 \u0e15\u0e31\u0e27 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/36248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/36248\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=36248"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=36248"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=36248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}