{"id":39487,"date":"2024-06-24T11:11:10","date_gmt":"2024-06-24T04:11:10","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=39487"},"modified":"2024-06-24T11:12:08","modified_gmt":"2024-06-24T04:12:08","slug":"%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/","title":{"rendered":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0"},"content":{"rendered":"<div id=\"modal-ready\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448830239_997734112141670_7035217962805039233_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39488\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448830239_997734112141670_7035217962805039233_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448830239_997734112141670_7035217962805039233_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448830239_997734112141670_7035217962805039233_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448830239_997734112141670_7035217962805039233_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448830239_997734112141670_7035217962805039233_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2567 \u0e40\u0e27\u0e25\u0e32 08.30 \u0e19.&nbsp; \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e17\u0e32\u0e17\u0e2d\u0e07 1&nbsp; \u0e0a\u0e31\u0e49\u0e19 2<br>\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 &nbsp;\u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e<br>\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48&nbsp; 3\/2567&nbsp; \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07 \u0e17\u0e1b\u0e2d. \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e17\u0e1b\u0e2d. <br>\u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01&nbsp; \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1e\u0e07\u0e29\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e28\u0e23\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e21\u0e07\u0e04\u0e25 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\/\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e15\u0e32\u0e21\u0e27\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f&nbsp; \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39521\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1-1024x683.jpg\" alt=\"\" class=\"wp-image-39521\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39524\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775847_997734268808321_4512819586960738023_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39524\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775847_997734268808321_4512819586960738023_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775847_997734268808321_4512819586960738023_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775847_997734268808321_4512819586960738023_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775847_997734268808321_4512819586960738023_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775847_997734268808321_4512819586960738023_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39527\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882601_997734205474994_958075004258964401_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39527\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882601_997734205474994_958075004258964401_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882601_997734205474994_958075004258964401_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882601_997734205474994_958075004258964401_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882601_997734205474994_958075004258964401_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882601_997734205474994_958075004258964401_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e42\u0e14\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e37\u0e2d<br>&nbsp;\u0e01\u0e34\u0e19-\u0e2d\u0e22\u0e39\u0e48-\u0e14\u0e35 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e27\u0e34\u0e23\u0e38\u0e2c\u0e2b\u0e4c \u0e28\u0e23\u0e35\u0e1a\u0e23\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br>\u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e01\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e30\u0e22\u0e01\u0e02\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (An automatic ankle pumping and leg lifting device) \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e07\u0e19\u0e38\u0e0a \u0e25\u0e48\u0e27\u0e07\u0e1e\u0e49\u0e19 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e28\u0e34\u0e23\u0e34\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e01\u0e39\u0e25\u0e32\u0e19\u0e38\u0e2a\u0e23\u0e13\u0e4c \u0e41\u0e25\u0e30 \u0e14\u0e23.\u0e01\u0e38\u0e25\u0e18\u0e34\u0e14\u0e32 \u0e01\u0e25\u0e49\u0e32\u0e23\u0e2d\u0e14&nbsp; \u0e04\u0e13\u0e30\u0e2a\u0e2b\u0e40\u0e27\u0e0a\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e20\u0e39\u0e21\u0e34\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e2a\u0e39\u0e48\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e32\u0e07\u0e1e\u0e32\u0e23\u0e32\u0e14\u0e49\u0e27\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 delayed-action gelling agent \u0e42\u0e14\u0e22 \u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32&nbsp; SUWAN Spray Betapinene \u0e04\u0e37\u0e2d \u0e2a\u0e40\u0e1b\u0e23\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e2a\u0e32\u0e23\u0e2a\u0e01\u0e31\u0e14\u0e08\u0e32\u0e01\u0e21\u0e30\u0e01\u0e23\u0e39\u0e14 \u0e25\u0e14\u0e1b\u0e27\u0e14\u0e2d\u0e31\u0e01\u0e40\u0e2a\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e32\u0e22\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15 GMP \u0e41\u0e25\u0e30\u0e21\u0e35\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2d\u0e19\u0e38\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1a\u0e31\u0e15\u0e23\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e2d\u0e07\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e1a\u0e48\u0e21\u0e40\u0e1e\u0e32\u0e30\u0e2f (UBI) \u0e41\u0e25\u0e30\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 &nbsp;TAMMA \u0e2a\u0e1a\u0e39\u0e48\u0e16\u0e48\u0e32\u0e19\u0e44\u0e21\u0e49\u0e44\u0e1c\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e38\u0e25\u0e1a \u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e32\u0e30\u0e0a\u0e49\u0e32\u0e07\u0e43\u0e15\u0e49\u0e42\u0e14\u0e22\u0e04\u0e13\u0e30\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e01\u0e35\u0e2c\u0e32 \u0e44\u0e14\u0e49\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 U2T &nbsp;\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35\u0e1b\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e02\u0e47\u0e21\u0e01\u0e25\u0e31\u0e14&nbsp; \u0e2a\u0e31\u0e0d\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e21\u0e35\u0e28\u0e23\u0e31\u0e17\u0e18\u0e32 \u0e21\u0e34\u0e15\u0e23\u0e20\u0e32\u0e1e \u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2a\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e0b\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e15\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e42\u0e14\u0e22 \u0e04\u0e13\u0e30\u0e2d\u0e31\u0e0d\u0e21\u0e13\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 &nbsp;\u0e01\u0e33\u0e44\u0e25\u0e2b\u0e34\u0e19 Howlite (\u0e2e\u0e32\u0e27\u0e44\u0e25\u0e15\u0e4c) Tiger eye (\u0e44\u0e17\u0e40\u0e01\u0e2d\u0e23\u0e4c\u0e2d\u0e32\u0e22) \u0e41\u0e25\u0e30 Lapis Lazuli (\u0e25\u0e32\u0e1e\u0e34\u0e0b \u0e25\u0e32\u0e0b\u0e39\u0e25\u0e35)<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39497\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448779012_997734078808340_2114649386557187572_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39497\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448779012_997734078808340_2114649386557187572_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448779012_997734078808340_2114649386557187572_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448779012_997734078808340_2114649386557187572_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448779012_997734078808340_2114649386557187572_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448779012_997734078808340_2114649386557187572_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39494\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882598_997734008808347_8891791369732080985_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39494\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882598_997734008808347_8891791369732080985_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882598_997734008808347_8891791369732080985_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882598_997734008808347_8891791369732080985_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882598_997734008808347_8891791369732080985_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882598_997734008808347_8891791369732080985_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39500\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448883751_997734032141678_6181086649861650203_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39500\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448883751_997734032141678_6181086649861650203_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448883751_997734032141678_6181086649861650203_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448883751_997734032141678_6181086649861650203_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448883751_997734032141678_6181086649861650203_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448883751_997734032141678_6181086649861650203_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39512\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775129_997734042141677_5088826763315955919_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39512\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775129_997734042141677_5088826763315955919_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775129_997734042141677_5088826763315955919_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775129_997734042141677_5088826763315955919_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775129_997734042141677_5088826763315955919_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448775129_997734042141677_5088826763315955919_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39503\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448778307_997734232141658_1189122043122038453_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39503\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448778307_997734232141658_1189122043122038453_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448778307_997734232141658_1189122043122038453_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448778307_997734232141658_1189122043122038453_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448778307_997734232141658_1189122043122038453_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448778307_997734232141658_1189122043122038453_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39518\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448812656_997734772141604_923732952484152312_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39518\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448812656_997734772141604_923732952484152312_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448812656_997734772141604_923732952484152312_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448812656_997734772141604_923732952484152312_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448812656_997734772141604_923732952484152312_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448812656_997734772141604_923732952484152312_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39509\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448829088_997734358808312_6510385178117167726_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39509\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448829088_997734358808312_6510385178117167726_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448829088_997734358808312_6510385178117167726_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448829088_997734358808312_6510385178117167726_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448829088_997734358808312_6510385178117167726_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448829088_997734358808312_6510385178117167726_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39515\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448832720_997734238808324_714328143943126581_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39515\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448832720_997734238808324_714328143943126581_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448832720_997734238808324_714328143943126581_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448832720_997734238808324_714328143943126581_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448832720_997734238808324_714328143943126581_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448832720_997734238808324_714328143943126581_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39506\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448851451_997734425474972_5129533835813328164_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39506\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448851451_997734425474972_5129533835813328164_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448851451_997734425474972_5129533835813328164_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448851451_997734425474972_5129533835813328164_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448851451_997734425474972_5129533835813328164_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448851451_997734425474972_5129533835813328164_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39539\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448881592_997734292141652_2397464946245647628_n-1024x683.jpg\" alt=\"\" class=\"wp-image-39539\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448881592_997734292141652_2397464946245647628_n-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448881592_997734292141652_2397464946245647628_n-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448881592_997734292141652_2397464946245647628_n-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448881592_997734292141652_2397464946245647628_n-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448881592_997734292141652_2397464946245647628_n.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39530\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448879014_997734535474961_8712452130692977624_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39530\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448879014_997734535474961_8712452130692977624_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448879014_997734535474961_8712452130692977624_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448879014_997734535474961_8712452130692977624_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448879014_997734535474961_8712452130692977624_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448879014_997734535474961_8712452130692977624_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"39536\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882097_997734435474971_609802630385897846_n_0-1024x683.jpg\" alt=\"\" class=\"wp-image-39536\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882097_997734435474971_609802630385897846_n_0-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882097_997734435474971_609802630385897846_n_0-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882097_997734435474971_609802630385897846_n_0-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882097_997734435474971_609802630385897846_n_0-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448882097_997734435474971_609802630385897846_n_0.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>","protected":false},"featured_media":39521,"parent":0,"template":"","agency":[],"news-type":[74],"class_list":["post-39487","new","type-new","status-publish","has-post-thumbnail","hentry","news-type-highlight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:description\" content=\"&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2567 \u0e40\u0e27\u0e25\u0e32 08.30 \u0e19.&nbsp; \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e17\u0e32\u0e17\u0e2d\u0e07 1&nbsp; \u0e0a\u0e31\u0e49\u0e19 2\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 &nbsp;\u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48&nbsp; 3\/2567&nbsp; \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07 \u0e17\u0e1b\u0e2d. \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e17\u0e1b\u0e2d. \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01&nbsp; \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1e\u0e07\u0e29\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e28\u0e23\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e21\u0e07\u0e04\u0e25 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\/\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e15\u0e32\u0e21\u0e27\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f&nbsp; \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e42\u0e14\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e37\u0e2d&nbsp;\u0e01\u0e34\u0e19-\u0e2d\u0e22\u0e39\u0e48-\u0e14\u0e35 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e27\u0e34\u0e23\u0e38\u0e2c\u0e2b\u0e4c \u0e28\u0e23\u0e35\u0e1a\u0e23\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e01\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e30\u0e22\u0e01\u0e02\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (An automatic ankle pumping and [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-24T04:12:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/\",\"url\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\"},\"datePublished\":\"2024-06-24T04:11:10+00:00\",\"dateModified\":\"2024-06-24T04:12:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.buu.ac.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.buu.ac.th\/en\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"contentUrl\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/","og_locale":"en_US","og_type":"article","og_title":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_description":"&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 22 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2567 \u0e40\u0e27\u0e25\u0e32 08.30 \u0e19.&nbsp; \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e17\u0e32\u0e17\u0e2d\u0e07 1&nbsp; \u0e0a\u0e31\u0e49\u0e19 2\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 &nbsp;\u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48&nbsp; 3\/2567&nbsp; \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e2d\u0e07 \u0e17\u0e1b\u0e2d. \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 \u0e17\u0e1b\u0e2d. \u0e43\u0e19\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01&nbsp; \u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e19\u0e32\u0e22\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e1e\u0e07\u0e29\u0e4c\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e28\u0e23\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e21\u0e07\u0e04\u0e25 \u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\/\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e41\u0e25\u0e30\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e15\u0e32\u0e21\u0e27\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f&nbsp; \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e42\u0e14\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2f \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e37\u0e2d&nbsp;\u0e01\u0e34\u0e19-\u0e2d\u0e22\u0e39\u0e48-\u0e14\u0e35 \u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21 \u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e02\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e27\u0e34\u0e23\u0e38\u0e2c\u0e2b\u0e4c \u0e28\u0e23\u0e35\u0e1a\u0e23\u0e34\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e23\u0e30\u0e14\u0e01\u0e02\u0e49\u0e2d\u0e40\u0e17\u0e49\u0e32\u0e41\u0e25\u0e30\u0e22\u0e01\u0e02\u0e32\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 (An automatic ankle pumping and [&hellip;]","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2024-06-24T04:12:08+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/06\/448773382_997734305474984_289928080590839742_n_0-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2024-06-24T04:11:10+00:00","dateModified":"2024-06-24T04:12:08+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2%e0%b8%9a%e0%b8%b9%e0%b8%a3%e0%b8%9e%e0%b8%b2-%e0%b9%80%e0%b8%9b%e0%b9%87%e0%b8%99%e0%b9%80%e0%b8%88\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e20\u0e32\u0e1e\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (\u0e17\u0e1b\u0e2d.) \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/39487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/39487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media\/39521"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=39487"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=39487"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=39487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}