{"id":41146,"date":"2024-07-15T10:00:23","date_gmt":"2024-07-15T03:00:23","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=41146"},"modified":"2024-07-15T14:21:12","modified_gmt":"2024-07-15T07:21:12","slug":"%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/","title":{"rendered":"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"},"content":{"rendered":"<div id=\"modal-ready\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0643-35-1024x683.jpg\" alt=\"\" class=\"wp-image-41147\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0643-35-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0643-35-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0643-35-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0643-35-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0643-35-2048x1366.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">           \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2567  \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 903 \u0e0a\u0e31\u0e49\u0e19 9 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 <br>\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e23\u0e28.\u0e14\u0e23.\u0e2a\u0e38\u0e21\u0e19\u0e15\u0e4c \u0e2a\u0e01\u0e25\u0e44\u0e0a\u0e22 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 <br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32  \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e42\u0e25\u0e48 <br>\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e \u0e16\u0e32\u0e27\u0e23\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e22\u0e01\u0e24\u0e15\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e23\u0e21\u0e22\u0e4c \u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e23\u0e2b\u0e31\u0e2a 62 <br>\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 76 <br>\u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">          \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e23\u0e28.\u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e21\u0e2d\u0e1a\u0e0a\u0e48\u0e2d\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35 <br>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32  \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e28. \u0e23.\u0e15.\u0e2d. \u0e14\u0e23.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23 \u0e15\u0e31\u0e19\u0e28\u0e34\u0e23\u0e34\u0e04\u0e07\u0e04\u0e25 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br>\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e08\u0e34\u0e23\u0e27\u0e31\u0e18 \u0e28\u0e34\u0e23\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07 2 \u0e04\u0e19\u0e14\u0e49\u0e27\u0e22<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41154\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0618-15-1024x683.jpg\" alt=\"\" class=\"wp-image-41154\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0618-15-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0618-15-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0618-15-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0618-15-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0618-15-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41160\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0631-26-1024x683.jpg\" alt=\"\" class=\"wp-image-41160\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0631-26-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0631-26-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0631-26-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0631-26-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0631-26-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">     <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41179\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0620-17-1024x683.jpg\" alt=\"\" class=\"wp-image-41179\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0620-17-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0620-17-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0620-17-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0620-17-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0620-17-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41182\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0623-19-1024x683.jpg\" alt=\"\" class=\"wp-image-41182\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0623-19-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0623-19-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0623-19-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0623-19-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0623-19-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41188\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0635-29-1024x683.jpg\" alt=\"\" class=\"wp-image-41188\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0635-29-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0635-29-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0635-29-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0635-29-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0635-29-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41173\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0611-9-1024x683.jpg\" alt=\"\" class=\"wp-image-41173\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0611-9-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0611-9-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0611-9-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0611-9-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0611-9-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41194\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0648-38-1024x683.jpg\" alt=\"\" class=\"wp-image-41194\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0648-38-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0648-38-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0648-38-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0648-38-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0648-38-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41191\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0638-31-1024x683.jpg\" alt=\"\" class=\"wp-image-41191\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0638-31-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0638-31-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0638-31-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0638-31-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0638-31-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41176\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0608-6-1024x683.jpg\" alt=\"\" class=\"wp-image-41176\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0608-6-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0608-6-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0608-6-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0608-6-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0608-6-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41185\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0613-11-1024x683.jpg\" alt=\"\" class=\"wp-image-41185\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0613-11-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0613-11-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0613-11-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0613-11-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0613-11-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"41197\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0599-1-1-1024x683.jpg\" alt=\"\" class=\"wp-image-41197\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0599-1-1-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0599-1-1-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0599-1-1-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0599-1-1-1536x1024.jpg 1536w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/IMG_0599-1-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"41207\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726035_888114756676948_6253331434402815485_n-1-819x1024.jpg\" alt=\"\" class=\"wp-image-41207\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726035_888114756676948_6253331434402815485_n-1-819x1024.jpg 819w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726035_888114756676948_6253331434402815485_n-1-240x300.jpg 240w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726035_888114756676948_6253331434402815485_n-1-768x960.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726035_888114756676948_6253331434402815485_n-1.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"41210\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726-819x1024.jpg\" alt=\"\" class=\"wp-image-41210\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726-819x1024.jpg 819w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726-240x300.jpg 240w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726-768x960.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449726.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">  \u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e \u0e16\u0e32\u0e27\u0e23\u0e2a\u0e38\u0e02 \u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e23\u0e2b\u0e31\u0e2a 62 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e17\u0e2d\u0e07<br> \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2565 \u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 76 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a><\/a>-\u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e31\u0e12\u0e19\u0e32\u0e19\u0e04\u0e23 \u0e1e.\u0e28. 2560-2562<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e17\u0e2d\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e1e.\u0e28. 2562 \u2013 2565<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 76 \u0e1e.\u0e28. 2566-2567<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; \u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e28\u0e32\u0e25\u0e2d\u0e32\u0e0d\u0e32\u0e04\u0e14\u0e35\u0e17\u0e38\u0e08\u0e23\u0e34\u0e15\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e1e\u0e24\u0e15\u0e34\u0e21\u0e34\u0e0a\u0e2d\u0e1a\u0e01\u0e25\u0e32\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 : <a href=\"https:\/\/www.facebook.com\/photo\/?fbid=888114760010281&amp;set=a.467491852072576\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/photo\/?fbid=888114760010281&amp;set=a.467491852072576<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"41213\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449777610_888112353343855_1530478359979626676_n-819x1024.jpg\" alt=\"\" class=\"wp-image-41213\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449777610_888112353343855_1530478359979626676_n-819x1024.jpg 819w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449777610_888112353343855_1530478359979626676_n-240x300.jpg 240w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449777610_888112353343855_1530478359979626676_n-768x960.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/449777610_888112353343855_1530478359979626676_n.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"41216\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/4497776165-819x1024.jpg\" alt=\"\" class=\"wp-image-41216\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/4497776165-819x1024.jpg 819w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/4497776165-240x300.jpg 240w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/4497776165-768x960.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/4497776165.jpg 960w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">     \u0e19\u0e32\u0e22\u0e01\u0e24\u0e15\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e23\u0e21\u0e22\u0e4c \u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e23\u0e2b\u0e31\u0e2a 62 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e40\u0e2b\u0e23\u0e35\u0e22\u0e0d\u0e17\u0e2d\u0e07 <br>\u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2565 \u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 76 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<br>.<br>\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32<br>&#8211; \u0e21\u0e31\u0e18\u0e22\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32\u0e15\u0e2d\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e0a\u0e25\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e2d\u0e33\u0e23\u0e38\u0e07 \u0e1e.\u0e28.2560 &#8211; 2562<br>&#8211; \u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e1e.\u0e28. 2562 &#8211; 2565<br>&#8211; \u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 76 \u0e1e.\u0e28. 2566-2567<br>.<br>\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<br>&#8211; \u0e17\u0e35\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e2a\u0e21\u0e32\u0e23\u0e4c\u0e17\u0e25\u0e2d\u0e27\u0e4c\u0e15\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 \u0e1e.\u0e28.2567 \u2013 \u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2d\u0e48\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 : <a href=\"https:\/\/www.facebook.com\/photo\/?fbid=888112350010522&amp;set=a.467491852072576\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.facebook.com\/photo\/?fbid=888112350010522&amp;set=a.467491852072576<\/a><\/p>\n<\/div>","protected":false},"featured_media":41261,"parent":0,"template":"","agency":[51],"news-type":[74],"class_list":["post-41146","new","type-new","status-publish","has-post-thumbnail","hentry","agency-51","news-type-highlight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2567 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 903 \u0e0a\u0e31\u0e49\u0e19 9 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e23\u0e28.\u0e14\u0e23.\u0e2a\u0e38\u0e21\u0e19\u0e15\u0e4c \u0e2a\u0e01\u0e25\u0e44\u0e0a\u0e22 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e42\u0e25\u0e48 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e \u0e16\u0e32\u0e27\u0e23\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e22\u0e01\u0e24\u0e15\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e23\u0e21\u0e22\u0e4c \u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e23\u0e2b\u0e31\u0e2a 62 \u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 76 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e23\u0e28.\u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e21\u0e2d\u0e1a\u0e0a\u0e48\u0e2d\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e28. \u0e23.\u0e15.\u0e2d. \u0e14\u0e23.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23 \u0e15\u0e31\u0e19\u0e28\u0e34\u0e23\u0e34\u0e04\u0e07\u0e04\u0e25 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e08\u0e34\u0e23\u0e27\u0e31\u0e18 \u0e28\u0e34\u0e23\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07 2 \u0e04\u0e19\u0e14\u0e49\u0e27\u0e22 &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; \u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-15T07:21:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35-copy.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/\",\"url\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/\",\"name\":\"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\"},\"datePublished\":\"2024-07-15T03:00:23+00:00\",\"dateModified\":\"2024-07-15T07:21:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.buu.ac.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.buu.ac.th\/en\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"contentUrl\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/","og_locale":"en_US","og_type":"article","og_title":"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_description":"\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 13 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2567 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 903 \u0e0a\u0e31\u0e49\u0e19 9 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e23\u0e28.\u0e14\u0e23.\u0e2a\u0e38\u0e21\u0e19\u0e15\u0e4c \u0e2a\u0e01\u0e25\u0e44\u0e0a\u0e22 \u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e44\u0e14\u0e49\u0e01\u0e25\u0e48\u0e32\u0e27\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e41\u0e25\u0e30\u0e21\u0e2d\u0e1a\u0e42\u0e25\u0e48 \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a \u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e \u0e16\u0e32\u0e27\u0e23\u0e2a\u0e38\u0e02 \u0e41\u0e25\u0e30 \u0e19\u0e32\u0e22\u0e01\u0e24\u0e15\u0e27\u0e31\u0e12\u0e19\u0e4c \u0e2a\u0e38\u0e27\u0e23\u0e23\u0e13\u0e23\u0e21\u0e22\u0e4c \u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e23\u0e2b\u0e31\u0e2a 62 \u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22\u0e2a\u0e21\u0e31\u0e22\u0e17\u0e35\u0e48 76 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e23\u0e28.\u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e21\u0e2d\u0e1a\u0e0a\u0e48\u0e2d\u0e14\u0e2d\u0e01\u0e44\u0e21\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e1c\u0e28. \u0e23.\u0e15.\u0e2d. \u0e14\u0e23.\u0e27\u0e34\u0e40\u0e0a\u0e35\u0e22\u0e23 \u0e15\u0e31\u0e19\u0e28\u0e34\u0e23\u0e34\u0e04\u0e07\u0e04\u0e25 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e08\u0e34\u0e23\u0e27\u0e31\u0e18 \u0e28\u0e34\u0e23\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e17\u0e31\u0e49\u0e07 2 \u0e04\u0e19\u0e14\u0e49\u0e27\u0e22 &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212; \u0e19\u0e32\u0e22\u0e1e\u0e23\u0e40\u0e17\u0e1e [&hellip;]","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2024-07-15T07:21:12+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/07\/\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35-copy.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/","name":"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2024-07-15T03:00:23+00:00","dateModified":"2024-07-15T07:21:12+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%99%e0%b8%b2%e0%b8%a2%e0%b8%81%e0%b8%aa%e0%b8%a0%e0%b8%b2%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97%e0%b8%a2%e0%b8%b2%e0%b8%a5%e0%b8%b1%e0%b8%a2-%e0%b9%81%e0%b8%aa%e0%b8%94%e0%b8%87\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e19\u0e32\u0e22\u0e01\u0e2a\u0e20\u0e32\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e22\u0e34\u0e19\u0e14\u0e35\u0e01\u0e31\u0e1a\u0e2a\u0e2d\u0e07\u0e28\u0e34\u0e29\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e32\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e1a\u0e40\u0e19\u0e15\u0e34\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e44\u0e17\u0e22 \u0e44\u0e14\u0e49\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e41\u0e25\u0e30 \u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 2 \u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/41146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/41146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media\/41261"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=41146"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=41146"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=41146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}