{"id":45182,"date":"2024-09-20T13:45:46","date_gmt":"2024-09-20T06:45:46","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=45182"},"modified":"2024-09-20T13:45:48","modified_gmt":"2024-09-20T06:45:48","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15"},"content":{"rendered":"<div id=\"modal-ready\">\n<p class=\"wp-block-paragraph\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e15\u0e38\u0e25\u0e32\u0e04\u0e21 \u0e1e.\u0e28. 2567 \u0e16\u0e36\u0e07 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e1e.\u0e28. 2568<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/affairs.buu.ac.th\/index.php\/main\/detail\/2022\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/a><\/p>\n<\/div>","protected":false},"featured_media":0,"parent":0,"template":"","agency":[40],"news-type":[39],"class_list":["post-45182","new","type-new","status-publish","hentry","agency-40","news-type-39"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"description\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:description\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-20T06:45:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/\",\"url\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\"},\"datePublished\":\"2024-09-20T06:45:46+00:00\",\"dateModified\":\"2024-09-20T06:45:48+00:00\",\"description\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15\",\"breadcrumb\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.buu.ac.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.buu.ac.th\/en\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"contentUrl\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_description":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2024-09-20T06:45:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/","name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2024-09-20T06:45:46+00:00","dateModified":"2024-09-20T06:45:48+00:00","description":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%9c%e0%b8%b9%e0%b9%89%e0%b8%8a%e0%b8%99%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b9%80%e0%b8%aa%e0%b8%99%e0%b8%ad%e0%b8%a3%e0%b8%b2-162\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e1c\u0e39\u0e49\u0e0a\u0e19\u0e30\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32 \u0e08\u0e49\u0e32\u0e07\u0e40\u0e2b\u0e21\u0e32\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e33\u0e08\u0e31\u0e14\u0e1b\u0e25\u0e27\u0e01 \u0e2b\u0e19\u0e39 \u0e41\u0e25\u0e30\u0e41\u0e21\u0e25\u0e07 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e2d\u0e1e\u0e31\u0e01\u0e19\u0e34\u0e2a\u0e34\u0e15"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/45182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/45182\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=45182"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=45182"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=45182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}