{"id":50072,"date":"2024-11-28T10:53:10","date_gmt":"2024-11-28T03:53:10","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=50072"},"modified":"2024-11-28T10:53:44","modified_gmt":"2024-11-28T03:53:44","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14"},"content":{"rendered":"<div id=\"modal-ready\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468567091_1009204287679361_2891964222656105003_n-1-1024x683.jpg\" alt=\"\" class=\"wp-image-50073\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468567091_1009204287679361_2891964222656105003_n-1-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468567091_1009204287679361_2891964222656105003_n-1-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468567091_1009204287679361_2891964222656105003_n-1-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468567091_1009204287679361_2891964222656105003_n-1.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">    \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e1e.\u0e28.2567 \u0e40\u0e27\u0e25\u0e32 09.30-11.30 \u0e19. (\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22)  \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e19\u0e42\u0e08\u0e27 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25 Zoom \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01<br>\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 (online) \u0e41\u0e25\u0e30 <br>Professor Li Xiaokun \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e19\u0e42\u0e08\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 <br>\u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e19\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd38\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f538.png\">\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e08\u0e23\u0e34\u0e15\u0e04\u0e27\u0e23 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd38\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f538.png\">\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e32\u0e23\u0e38\u0e13 \u0e2a\u0e38\u0e02\u0e2a\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 (online)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd38\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f538.png\">\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e1e\u0e23\u0e23\u0e13\u0e27\u0e25\u0e31\u0e22 \u0e40\u0e01\u0e27\u0e30\u0e23\u0e30 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd38\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f538.png\">\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e1e.\u0e01\u0e34\u0e15\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e01\u0e23\u0e40\u0e1e\u0e0a\u0e23 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c (online) <br>(\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd38\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f538.png\">\u0e04\u0e38\u0e13\u0e14\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2a\u0e38\u0e23\u0e31\u0e01\u0e02\u0e01\u0e30 \u0e23\u0e2d\u0e07\u0e1b\u0e25\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 (\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udd38\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/t72\/1\/16\/1f538.png\">\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e20\u0e39\u0e21\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c\u0e40\u0e25\u0e34\u0e28\u0e2d\u0e21\u0e23 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">     \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\u0e21\u0e35\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e14\u0e35\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e02\u0e48\u0e32\u0e27\u0e09\u0e1a\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e08\u0e35\u0e19 :<a href=\"https:\/\/mp.weixin.qq.com\/s\/YVYPQkfe2PEKC59ElXsIgQ?fbclid=IwZXh0bgNhZW0CMTAAAR0cgZeiWkDIjCtP8_XyEvumamtxzBb5FLKztpQ8_Owqu46DsOKPaS0-p4c_aem_N6YL3opCyPRRyv9u8CaK5Q\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/mp.weixin.qq.com\/s\/YVYPQkfe2PEKC59ElXsIgQ<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50076\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2-1024x683.jpg\" alt=\"\" class=\"wp-image-50076\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50085\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468594061_1009204411012682_3979663396858790307_n-3-1024x683.jpg\" alt=\"\" class=\"wp-image-50085\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468594061_1009204411012682_3979663396858790307_n-3-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468594061_1009204411012682_3979663396858790307_n-3-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468594061_1009204411012682_3979663396858790307_n-3-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468594061_1009204411012682_3979663396858790307_n-3.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50088\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468625845_1009204507679339_8507140517357071847_n-4-1024x683.jpg\" alt=\"\" class=\"wp-image-50088\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468625845_1009204507679339_8507140517357071847_n-4-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468625845_1009204507679339_8507140517357071847_n-4-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468625845_1009204507679339_8507140517357071847_n-4-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468625845_1009204507679339_8507140517357071847_n-4.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50079\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468452929_1009204414346015_8345305520180166876_n-6-1024x683.jpg\" alt=\"\" class=\"wp-image-50079\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468452929_1009204414346015_8345305520180166876_n-6-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468452929_1009204414346015_8345305520180166876_n-6-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468452929_1009204414346015_8345305520180166876_n-6-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468452929_1009204414346015_8345305520180166876_n-6.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50094\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468512642_1009204494346007_6035396103054508069_n-7-1024x683.jpg\" alt=\"\" class=\"wp-image-50094\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468512642_1009204494346007_6035396103054508069_n-7-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468512642_1009204494346007_6035396103054508069_n-7-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468512642_1009204494346007_6035396103054508069_n-7-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468512642_1009204494346007_6035396103054508069_n-7.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50082\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468454502_1009204417679348_7014842291271901309_n-5-1024x683.jpg\" alt=\"\" class=\"wp-image-50082\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468454502_1009204417679348_7014842291271901309_n-5-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468454502_1009204417679348_7014842291271901309_n-5-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468454502_1009204417679348_7014842291271901309_n-5-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468454502_1009204417679348_7014842291271901309_n-5.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"50091\" src=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468610375_1009204511012672_1712641639588385283_n-8-1024x683.jpg\" alt=\"\" class=\"wp-image-50091\" srcset=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468610375_1009204511012672_1712641639588385283_n-8-1024x683.jpg 1024w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468610375_1009204511012672_1712641639588385283_n-8-300x200.jpg 300w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468610375_1009204511012672_1712641639588385283_n-8-768x512.jpg 768w, https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468610375_1009204511012672_1712641639588385283_n-8.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n<\/div>","protected":false},"featured_media":50076,"parent":0,"template":"","agency":[],"news-type":[74],"class_list":["post-50072","new","type-new","status-publish","has-post-thumbnail","hentry","news-type-highlight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:description\" content=\"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e1e.\u0e28.2567 \u0e40\u0e27\u0e25\u0e32 09.30-11.30 \u0e19. (\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e19\u0e42\u0e08\u0e27 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25 Zoom \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 (online) \u0e41\u0e25\u0e30 Professor Li Xiaokun \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e19\u0e42\u0e08\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e19\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e08\u0e23\u0e34\u0e15\u0e04\u0e27\u0e23 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e32\u0e23\u0e38\u0e13 \u0e2a\u0e38\u0e02\u0e2a\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 (online) \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e1e\u0e23\u0e23\u0e13\u0e27\u0e25\u0e31\u0e22 \u0e40\u0e01\u0e27\u0e30\u0e23\u0e30 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e1e.\u0e01\u0e34\u0e15\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e01\u0e23\u0e40\u0e1e\u0e0a\u0e23 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c (online) (\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c) \u0e04\u0e38\u0e13\u0e14\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2a\u0e38\u0e23\u0e31\u0e01\u0e02\u0e01\u0e30 \u0e23\u0e2d\u0e07\u0e1b\u0e25\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 (\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T03:53:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/\",\"url\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\"},\"datePublished\":\"2024-11-28T03:53:10+00:00\",\"dateModified\":\"2024-11-28T03:53:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.buu.ac.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.buu.ac.th\/en\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"contentUrl\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/","og_locale":"en_US","og_type":"article","og_title":"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_description":"\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 20 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 \u0e1e.\u0e28.2567 \u0e40\u0e27\u0e25\u0e32 09.30-11.30 \u0e19. (\u0e40\u0e27\u0e25\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e19\u0e42\u0e08\u0e27 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e17\u0e32\u0e07\u0e44\u0e01\u0e25 Zoom \u0e42\u0e14\u0e22\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e08\u0e32\u0e01\u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e31\u0e0a\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e01\u0e32\u0e2a\u0e25\u0e31\u0e01 \u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e32\u0e01\u0e32\u0e23\u0e41\u0e17\u0e19\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 (online) \u0e41\u0e25\u0e30 Professor Li Xiaokun \u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e40\u0e27\u0e34\u0e19\u0e42\u0e08\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e23\u0e32\u0e22\u0e19\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e1d\u0e48\u0e32\u0e22\u0e44\u0e17\u0e22\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e2a\u0e21\u0e16\u0e27\u0e34\u0e25 \u0e08\u0e23\u0e34\u0e15\u0e04\u0e27\u0e23 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e01\u0e32\u0e23\u0e38\u0e13 \u0e2a\u0e38\u0e02\u0e2a\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07 \u0e23\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 (online) \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e1e\u0e23\u0e23\u0e13\u0e27\u0e25\u0e31\u0e22 \u0e40\u0e01\u0e27\u0e30\u0e23\u0e30 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e2d\u0e18\u0e34\u0e01\u0e32\u0e23\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e23\u0e2d\u0e07\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e1e.\u0e01\u0e34\u0e15\u0e15\u0e34 \u0e01\u0e23\u0e38\u0e07\u0e44\u0e01\u0e23\u0e40\u0e1e\u0e0a\u0e23 \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e27\u0e34\u0e40\u0e17\u0e28\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c (online) (\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c) \u0e04\u0e38\u0e13\u0e14\u0e32\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e2a\u0e38\u0e23\u0e31\u0e01\u0e02\u0e01\u0e30 \u0e23\u0e2d\u0e07\u0e1b\u0e25\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35 (\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e19\u0e32\u0e22\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2a\u0e48\u0e27\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e0a\u0e25\u0e1a\u0e38\u0e23\u0e35) [&hellip;]","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2024-11-28T03:53:44+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/11\/468523536_1009204284346028_6553290257935591207_n-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/","name":"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2024-11-28T03:53:10+00:00","dateModified":"2024-11-28T03:53:44+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%ad%e0%b8%b3%e0%b8%99%e0%b8%a7%e0%b8%a2%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%aa%e0%b8%96%e0%b8%b2%e0%b8%9a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d \u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e23\u0e38\u0e1b\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e02\u0e07\u0e08\u0e37\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 14"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/50072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":0,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/50072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media\/50076"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=50072"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=50072"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=50072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}