{"id":74692,"date":"2026-03-18T15:56:36","date_gmt":"2026-03-18T08:56:36","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=74692"},"modified":"2026-03-18T15:56:36","modified_gmt":"2026-03-18T08:56:36","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07"},"content":{"rendered":"<div id=\"modal-ready\">\n<div class=\"wp-block-file\"><object class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/03\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d-\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d-\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49.\"><\/object><a id=\"wp-block-file--media-46b9eb8e-e027-4708-b1e5-90870d78235e\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/03\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d-\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49.pdf\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d-\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/03\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d-\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-46b9eb8e-e027-4708-b1e5-90870d78235e\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n<\/div>","protected":false},"featured_media":37956,"parent":0,"template":"","agency":[52],"news-type":[39],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/05\/campus81_09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"568\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/\",\"url\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/\",\"name\":\"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\"},\"datePublished\":\"2026-03-18T08:56:36+00:00\",\"dateModified\":\"2026-03-18T08:56:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.buu.ac.th\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/www.buu.ac.th\/en\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#website\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\/\/www.buu.ac.th\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"contentUrl\":\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/","og_locale":"en_US","og_type":"article","og_title":"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_image":[{"width":1000,"height":568,"url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2024\/05\/campus81_09.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/","name":"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2026-03-18T08:56:36+00:00","dateModified":"2026-03-18T08:56:36+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b9%82%e0%b8%a5%e0%b8%88%e0%b8%b4%e0%b8%aa%e0%b8%95%e0%b8%b4%e0%b8%81%e0%b8%aa%e0%b9%8c-%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b8%aa%e0%b8%b2-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e04\u0e13\u0e30\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e2a\u0e31\u0e0d\u0e0d\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e08\u0e31\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e40\u0e01\u0e49\u0e32\u0e2d\u0e35\u0e49\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19 \u0e42\u0e14\u0e22\u0e27\u0e34\u0e18\u0e35\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e08\u0e32\u0e30\u0e08\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/74692"}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":1,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/74692\/revisions"}],"predecessor-version":[{"id":74695,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/74692\/revisions\/74695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media\/37956"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=74692"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=74692"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=74692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}