{"id":83344,"date":"2026-08-18T16:34:03","date_gmt":"2026-08-18T09:34:03","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=83344"},"modified":"2026-08-18T16:34:04","modified_gmt":"2026-08-18T09:34:04","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)"},"content":{"rendered":"<div id=\"modal-ready\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48-04902569-2.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 04902569.\"><\/object><a id=\"wp-block-file--media-e9a18304-9817-4933-9382-8de842d22c90\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48-04902569-2.pdf\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48 04902569<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e02\u0e17\u0e35\u0e48-04902569-2.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e9a18304-9817-4933-9382-8de842d22c90\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32.\"><\/object><a id=\"wp-block-file--media-0d8be4f6-d599-42c8-846c-228f4648eeba\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32-1.pdf\">\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-0d8be4f6-d599-42c8-846c-228f4648eeba\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19.\"><\/object><a id=\"wp-block-file--media-4467b5ff-3f7a-4c3e-b2c0-bf86022b2dac\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19-1.pdf\">\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-4467b5ff-3f7a-4c3e-b2c0-bf86022b2dac\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e.\"><\/object><a id=\"wp-block-file--media-2e909acf-265f-4be6-822d-8f2ad879481d\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e-1.pdf\">\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e2a\u0e40\u0e1b\u0e04\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-2e909acf-265f-4be6-822d-8f2ad879481d\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e15\u0e32\u0e23\u0e32\u0e07\u0e1b\u0e1b\u0e0a-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e15\u0e32\u0e23\u0e32\u0e07\u0e1b\u0e1b\u0e0a.\"><\/object><a id=\"wp-block-file--media-e779ce8f-815a-4304-ab80-7b9b0f1a27c3\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e15\u0e32\u0e23\u0e32\u0e07\u0e1b\u0e1b\u0e0a-1.pdf\">\u0e15\u0e32\u0e23\u0e32\u0e07\u0e1b\u0e1b\u0e0a<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/08\/\u0e15\u0e32\u0e23\u0e32\u0e07\u0e1b\u0e1b\u0e0a-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e779ce8f-815a-4304-ab80-7b9b0f1a27c3\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n<\/div>","protected":false},"featured_media":0,"parent":0,"template":"","agency":[48],"news-type":[39],"class_list":["post-83344","new","type-new","status-publish","hentry","agency-48","news-type-39"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-18T09:34:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\\\/\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\\\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#website\"},\"datePublished\":\"2026-08-18T09:34:03+00:00\",\"dateModified\":\"2026-08-18T09:34:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.buu.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2026-08-18T09:34:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/","name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding) - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2026-08-18T09:34:03+00:00","dateModified":"2026-08-18T09:34:04+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-97\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e0a\u0e38\u0e14\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e21\u0e37\u0e2d\u0e1c\u0e48\u0e32\u0e15\u0e31\u0e14\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e49\u0e2d\u0e07\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e30\u0e1a\u0e1a\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e20\u0e32\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e0a\u0e38\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e18\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c (e-bidding)"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/83344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":1,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/83344\/revisions"}],"predecessor-version":[{"id":83359,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/83344\/revisions\/83359"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=83344"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=83344"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=83344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}