{"id":84737,"date":"2026-09-01T18:25:02","date_gmt":"2026-09-01T11:25:02","guid":{"rendered":"https:\/\/www.buu.ac.th\/?post_type=new&#038;p=84737"},"modified":"2026-09-01T18:25:03","modified_gmt":"2026-09-01T11:25:03","slug":"%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120","status":"publish","type":"new","link":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/","title":{"rendered":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07"},"content":{"rendered":"<div id=\"modal-ready\">\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28.\"><\/object><a id=\"wp-block-file--media-485e31c9-1c38-496a-9ce9-8d0dafc28bc6\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28.pdf\">\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-485e31c9-1c38-496a-9ce9-8d0dafc28bc6\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32.\"><\/object><a id=\"wp-block-file--media-99acf493-1716-4e54-bcbf-bb4ff884d407\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32.pdf\">\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-99acf493-1716-4e54-bcbf-bb4ff884d407\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19.\"><\/object><a id=\"wp-block-file--media-16805ac7-5cef-4b7a-9536-0325905779ff\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19.pdf\">\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e23\u0e48\u0e32\u0e07\u0e02\u0e2d\u0e1a\u0e40\u0e02\u0e15\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-16805ac7-5cef-4b7a-9536-0325905779ff\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e2a\u0e40\u0e1b\u0e04.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of \u0e2a\u0e40\u0e1b\u0e04.\"><\/object><a id=\"wp-block-file--media-e3306611-4c3e-4a13-a0ef-27a6b1fddd72\" href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e2a\u0e40\u0e1b\u0e04.pdf\">\u0e2a\u0e40\u0e1b\u0e04<\/a><a href=\"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2026\/09\/\u0e2a\u0e40\u0e1b\u0e04.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e3306611-4c3e-4a13-a0ef-27a6b1fddd72\">\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14<\/a><\/div>\n<\/div>","protected":false},"featured_media":0,"parent":0,"template":"","agency":[48],"news-type":[39],"class_list":["post-84737","new","type-new","status-publish","hentry","agency-48","news-type-39"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T11:25:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\\\/\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\\\/\",\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#website\"},\"datePublished\":\"2026-09-01T11:25:02+00:00\",\"dateModified\":\"2026-09-01T11:25:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#organization\",\"name\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.buu.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-1.png\",\"contentUrl\":\"https:\\\/\\\/www.buu.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logo-1.png\",\"width\":442,\"height\":239,\"caption\":\"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32\"},\"image\":{\"@id\":\"https:\\\/\\\/www.buu.ac.th\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/","og_locale":"en_US","og_type":"article","og_title":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","og_url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/","og_site_name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","article_modified_time":"2026-09-01T11:25:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/","url":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/","name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07 - \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","isPartOf":{"@id":"https:\/\/www.buu.ac.th\/en\/#website"},"datePublished":"2026-09-01T11:25:02+00:00","dateModified":"2026-09-01T11:25:03+00:00","breadcrumb":{"@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.buu.ac.th\/en\/news\/%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b2%e0%b8%a8%e0%b9%82%e0%b8%a3%e0%b8%87%e0%b8%9e%e0%b8%a2%e0%b8%b2%e0%b8%9a%e0%b8%b2%e0%b8%a5%e0%b8%a1%e0%b8%ab%e0%b8%b2%e0%b8%a7%e0%b8%b4%e0%b8%97-120\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.buu.ac.th\/en\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/www.buu.ac.th\/en\/news\/"},{"@type":"ListItem","position":3,"name":"\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e42\u0e23\u0e07\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e23\u0e32\u0e04\u0e32\u0e40\u0e0a\u0e48\u0e32\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e2d\u0e01\u0e0b\u0e40\u0e23\u0e22\u0e4c\u0e1f\u0e25\u0e39\u0e42\u0e2d\u0e42\u0e23\u0e2a\u0e42\u0e04\u0e1b\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e1a\u0e1a\u0e0b\u0e35\u0e2d\u0e32\u0e23\u0e4c\u0e21\u0e01\u0e33\u0e25\u0e31\u0e07\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e01\u0e27\u0e48\u0e32 15 kw \u0e08\u0e33\u0e19\u0e27\u0e19 1 \u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07"}]},{"@type":"WebSite","@id":"https:\/\/www.buu.ac.th\/en\/#website","url":"https:\/\/www.buu.ac.th\/en\/","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","description":"","publisher":{"@id":"https:\/\/www.buu.ac.th\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.buu.ac.th\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.buu.ac.th\/en\/#organization","name":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32","url":"https:\/\/www.buu.ac.th\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","contentUrl":"https:\/\/www.buu.ac.th\/wp-content\/uploads\/2023\/04\/logo-1.png","width":442,"height":239,"caption":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e1a\u0e39\u0e23\u0e1e\u0e32"},"image":{"@id":"https:\/\/www.buu.ac.th\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/84737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/types\/new"}],"version-history":[{"count":1,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/84737\/revisions"}],"predecessor-version":[{"id":84746,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/new\/84737\/revisions\/84746"}],"wp:attachment":[{"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/media?parent=84737"}],"wp:term":[{"taxonomy":"agency","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/agency?post=84737"},{"taxonomy":"news-type","embeddable":true,"href":"https:\/\/www.buu.ac.th\/en\/wp-json\/wp\/v2\/news-type?post=84737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}